{"id":45379,"date":"2026-07-07T09:24:29","date_gmt":"2026-07-07T07:24:29","guid":{"rendered":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/"},"modified":"2026-07-07T09:24:32","modified_gmt":"2026-07-07T07:24:32","slug":"chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili","status":"publish","type":"product","link":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/","title":{"rendered":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris"},"content":{"rendered":"<p>Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris<\/p>\n","protected":false},"featured_media":44672,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[22],"product_tag":[85],"class_list":{"0":"post-45379","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mobilier-design-haut-de-gamme","7":"product_tag-vente-du-07-juillet-2026c","9":"first","10":"instock","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres\" \/>\n<meta property=\"og:description\" content=\"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/\" \/>\n<meta property=\"og:site_name\" content=\"wpe-encheres\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:24:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f5c8e7c8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"564\" \/>\n\t<meta property=\"og:image:height\" content=\"993\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/\",\"name\":\"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f5c8e7c8.jpg\",\"datePublished\":\"2026-07-07T07:24:29+00:00\",\"dateModified\":\"2026-07-07T07:24:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f5c8e7c8.jpg\",\"contentUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f5c8e7c8.jpg\",\"width\":564,\"height\":993},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/?page_id=22765\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\",\"name\":\"wpe-encheres\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#organization\",\"name\":\"wpe encheres\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wpe-encheres-logo.png\",\"contentUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wpe-encheres-logo.png\",\"width\":300,\"height\":110,\"caption\":\"wpe encheres\"},\"image\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/","og_locale":"fr_FR","og_type":"article","og_title":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","og_description":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris","og_url":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/","og_site_name":"wpe-encheres","article_modified_time":"2026-07-07T07:24:32+00:00","og_image":[{"width":564,"height":993,"url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f5c8e7c8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/","url":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/","name":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","isPartOf":{"@id":"https:\/\/wpe-encheres.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/#primaryimage"},"image":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/#primaryimage"},"thumbnailUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f5c8e7c8.jpg","datePublished":"2026-07-07T07:24:29+00:00","dateModified":"2026-07-07T07:24:32+00:00","breadcrumb":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/#primaryimage","url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f5c8e7c8.jpg","contentUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f5c8e7c8.jpg","width":564,"height":993},{"@type":"BreadcrumbList","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-haute-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-gris-pietement-en-acier-chrome-avec-repose-pieds-110-x-46-x-60-cm-localisation-54-avenue-phili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/wpe-encheres.com\/site\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/wpe-encheres.com\/site\/?page_id=22765"},{"@type":"ListItem","position":3,"name":"Chaise haute empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 gris, pi\u00e9tement en acier chrom\u00e9 avec repose-pieds. 110 x 46 x 60 cm. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris"}]},{"@type":"WebSite","@id":"https:\/\/wpe-encheres.com\/site\/#website","url":"https:\/\/wpe-encheres.com\/site\/","name":"wpe-encheres","description":"","publisher":{"@id":"https:\/\/wpe-encheres.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wpe-encheres.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wpe-encheres.com\/site\/#organization","name":"wpe encheres","url":"https:\/\/wpe-encheres.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wpe-encheres.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2025\/08\/wpe-encheres-logo.png","contentUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2025\/08\/wpe-encheres-logo.png","width":300,"height":110,"caption":"wpe encheres"},"image":{"@id":"https:\/\/wpe-encheres.com\/site\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product\/45379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/media\/44672"}],"wp:attachment":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/media?parent=45379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_brand?post=45379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_cat?post=45379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_tag?post=45379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}