{"id":45373,"date":"2026-07-07T09:24:29","date_gmt":"2026-07-07T07:24:29","guid":{"rendered":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/"},"modified":"2026-07-07T09:24:30","modified_gmt":"2026-07-07T07:24:30","slug":"chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni","status":"publish","type":"product","link":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/","title":{"rendered":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris"},"content":{"rendered":"<p>Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211;&#8230;<\/p>\n","protected":false},"featured_media":44642,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[22],"product_tag":[85],"class_list":{"0":"post-45373","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mobilier-design-haut-de-gamme","7":"product_tag-vente-du-07-juillet-2026c","9":"first","10":"instock","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&#039;usage). 3 unit\u00e9s. Vendu \u00e0 l&#039;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&#039;usage). 3 unit\u00e9s. Vendu \u00e0 l&#039;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres\" \/>\n<meta property=\"og:description\" content=\"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/\" \/>\n<meta property=\"og:site_name\" content=\"wpe-encheres\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T07:24:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f533b4de.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"814\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/\",\"name\":\"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d'usage). 3 unit\u00e9s. Vendu \u00e0 l'unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f533b4de.jpg\",\"datePublished\":\"2026-07-07T07:24:29+00:00\",\"dateModified\":\"2026-07-07T07:24:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f533b4de.jpg\",\"contentUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/6a356f533b4de.jpg\",\"width\":545,\"height\":814},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/produit\\\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/?page_id=22765\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\",\"name\":\"wpe-encheres\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#organization\",\"name\":\"wpe encheres\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wpe-encheres-logo.png\",\"contentUrl\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wpe-encheres-logo.png\",\"width\":300,\"height\":110,\"caption\":\"wpe encheres\"},\"image\":{\"@id\":\"https:\\\/\\\/wpe-encheres.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d'usage). 3 unit\u00e9s. Vendu \u00e0 l'unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/","og_locale":"fr_FR","og_type":"article","og_title":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d'usage). 3 unit\u00e9s. Vendu \u00e0 l'unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","og_description":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211;...","og_url":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/","og_site_name":"wpe-encheres","article_modified_time":"2026-07-07T07:24:30+00:00","og_image":[{"width":545,"height":814,"url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f533b4de.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/","url":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/","name":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d'usage). 3 unit\u00e9s. Vendu \u00e0 l'unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste - 75011 Paris - wpe-encheres","isPartOf":{"@id":"https:\/\/wpe-encheres.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/#primaryimage"},"image":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/#primaryimage"},"thumbnailUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f533b4de.jpg","datePublished":"2026-07-07T07:24:29+00:00","dateModified":"2026-07-07T07:24:30+00:00","breadcrumb":{"@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/#primaryimage","url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f533b4de.jpg","contentUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2026\/06\/6a356f533b4de.jpg","width":545,"height":814},{"@type":"BreadcrumbList","@id":"https:\/\/wpe-encheres.com\/site\/produit\/chaise-empilable-design-arne-jacobsen-modele-serie-7-edition-fritz-hansen-coque-en-bois-laque-couleur-orange-pietement-en-acier-chrome-79-x-51-x-52-cm-qq-usures-dusage-3-unites-vendu-a-luni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/wpe-encheres.com\/site\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/wpe-encheres.com\/site\/?page_id=22765"},{"@type":"ListItem","position":3,"name":"Chaise empilable design Arne Jacobsen mod\u00e8le S\u00e9rie 7, \u00e9dition Fritz Hansen, coque en bois laqu\u00e9 couleur orange, pi\u00e9tement en acier chrom\u00e9. 79 x 51 x 52 cm. (qq usures d&rsquo;usage). 3 unit\u00e9s. Vendu \u00e0 l&rsquo;unit\u00e9 avec facult\u00e9 de r\u00e9union. Localisation: 54 avenue Philippe Auguste &#8211; 75011 Paris"}]},{"@type":"WebSite","@id":"https:\/\/wpe-encheres.com\/site\/#website","url":"https:\/\/wpe-encheres.com\/site\/","name":"wpe-encheres","description":"","publisher":{"@id":"https:\/\/wpe-encheres.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wpe-encheres.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wpe-encheres.com\/site\/#organization","name":"wpe encheres","url":"https:\/\/wpe-encheres.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wpe-encheres.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2025\/08\/wpe-encheres-logo.png","contentUrl":"https:\/\/wpe-encheres.com\/site\/wp-content\/uploads\/2025\/08\/wpe-encheres-logo.png","width":300,"height":110,"caption":"wpe encheres"},"image":{"@id":"https:\/\/wpe-encheres.com\/site\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product\/45373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/media\/44642"}],"wp:attachment":[{"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/media?parent=45373"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_brand?post=45373"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_cat?post=45373"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/wpe-encheres.com\/site\/wp-json\/wp\/v2\/product_tag?post=45373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}